{"id":7375,"date":"2021-12-04T14:02:42","date_gmt":"2021-12-04T14:02:42","guid":{"rendered":"https:\/\/dbwc.eu\/?p=7375"},"modified":"2021-12-16T14:59:39","modified_gmt":"2021-12-16T14:59:39","slug":"jahresabschlussball-2021","status":"publish","type":"post","link":"https:\/\/dbwc.eu\/en\/jahresabschlussball-2021\/","title":{"rendered":"New Year&#8217;s ball 2021"},"content":{"rendered":"<p>Our New Year&#8217;s Ball took place on December 4th, at which the DBWC members decided to remember everything that had happened again.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Our New Year&#8217;s Ball took place on December 4th, at [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7385,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"Post_blog_tamplate.php","format":"standard","meta":{"footnotes":""},"categories":[54,2],"tags":[],"class_list":["post-7375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-event","category-news"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","ru","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New Year&#039;s ball 2021 - DBWC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dbwc.eu\/jahresabschlussball-2021\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Year&#039;s ball 2021 - DBWC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dbwc.eu\/jahresabschlussball-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"DBWC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/deutschbelarussischer.wirtschaftsclub.9\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-04T14:02:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-16T14:59:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dbwc.eu\/wp-content\/uploads\/2021\/12\/265240335_650432499287729_6098413531091205400_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2038\" \/>\n\t<meta property=\"og:image:height\" content=\"1359\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marina.veremchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"marina.veremchuk\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/\"},\"author\":{\"name\":\"marina.veremchuk\",\"@id\":\"https:\\\/\\\/dbwc.eu\\\/#\\\/schema\\\/person\\\/cd3662647974d17cdf3fd25498138a4a\"},\"headline\":\"New Year&#8217;s ball 2021\",\"datePublished\":\"2021-12-04T14:02:42+00:00\",\"dateModified\":\"2021-12-16T14:59:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/\"},\"wordCount\":71,\"publisher\":{\"@id\":\"https:\\\/\\\/dbwc.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dbwc.eu\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/265240335_650432499287729_6098413531091205400_n.jpg\",\"articleSection\":[\"Events\",\"News\"],\"inLanguage\":\"en-UK\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/\",\"url\":\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/\",\"name\":\"New Year's ball 2021 - DBWC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dbwc.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dbwc.eu\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/265240335_650432499287729_6098413531091205400_n.jpg\",\"datePublished\":\"2021-12-04T14:02:42+00:00\",\"dateModified\":\"2021-12-16T14:59:39+00:00\",\"description\":\"DBWC\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/#breadcrumb\"},\"inLanguage\":\"en-UK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-UK\",\"@id\":\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dbwc.eu\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/265240335_650432499287729_6098413531091205400_n.jpg\",\"contentUrl\":\"https:\\\/\\\/dbwc.eu\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/265240335_650432499287729_6098413531091205400_n.jpg\",\"width\":2038,\"height\":1359},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dbwc.eu\\\/jahresabschlussball-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/dbwc.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jahresabschlussball 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dbwc.eu\\\/#website\",\"url\":\"https:\\\/\\\/dbwc.eu\\\/\",\"name\":\"DBWC\",\"description\":\"Deutsch Belarussischer Wirtschaftsclub\",\"publisher\":{\"@id\":\"https:\\\/\\\/dbwc.eu\\\/#organization\"},\"alternateName\":\"Deutsch-Belarussischer Wirtschaftsclub\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dbwc.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-UK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dbwc.eu\\\/#organization\",\"name\":\"Deutsch-Belarussischer Wirtschaftsclub e.V.\",\"url\":\"https:\\\/\\\/dbwc.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-UK\",\"@id\":\"https:\\\/\\\/dbwc.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dbwc.eu\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/dbwc.eu\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logo.svg\",\"width\":237,\"height\":69,\"caption\":\"Deutsch-Belarussischer Wirtschaftsclub e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/dbwc.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/deutschbelarussischer.wirtschaftsclub.9\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/deutsch-belarussischer-wirtschaftsclub-e-v\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dbwc.eu\\\/#\\\/schema\\\/person\\\/cd3662647974d17cdf3fd25498138a4a\",\"name\":\"marina.veremchuk\",\"url\":\"https:\\\/\\\/dbwc.eu\\\/en\\\/author\\\/marina-veremchuk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New Year's ball 2021 - DBWC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/","og_locale":"en_US","og_type":"article","og_title":"New Year's ball 2021 - DBWC","og_url":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/","og_site_name":"DBWC","article_publisher":"https:\/\/www.facebook.com\/deutschbelarussischer.wirtschaftsclub.9","article_published_time":"2021-12-04T14:02:42+00:00","article_modified_time":"2021-12-16T14:59:39+00:00","og_image":[{"width":2038,"height":1359,"url":"https:\/\/dbwc.eu\/wp-content\/uploads\/2021\/12\/265240335_650432499287729_6098413531091205400_n.jpg","type":"image\/jpeg"}],"author":"marina.veremchuk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"marina.veremchuk"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/#article","isPartOf":{"@id":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/"},"author":{"name":"marina.veremchuk","@id":"https:\/\/dbwc.eu\/#\/schema\/person\/cd3662647974d17cdf3fd25498138a4a"},"headline":"New Year&#8217;s ball 2021","datePublished":"2021-12-04T14:02:42+00:00","dateModified":"2021-12-16T14:59:39+00:00","mainEntityOfPage":{"@id":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/"},"wordCount":71,"publisher":{"@id":"https:\/\/dbwc.eu\/#organization"},"image":{"@id":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/dbwc.eu\/wp-content\/uploads\/2021\/12\/265240335_650432499287729_6098413531091205400_n.jpg","articleSection":["Events","News"],"inLanguage":"en-UK"},{"@type":"WebPage","@id":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/","url":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/","name":"New Year's ball 2021 - DBWC","isPartOf":{"@id":"https:\/\/dbwc.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/#primaryimage"},"image":{"@id":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/dbwc.eu\/wp-content\/uploads\/2021\/12\/265240335_650432499287729_6098413531091205400_n.jpg","datePublished":"2021-12-04T14:02:42+00:00","dateModified":"2021-12-16T14:59:39+00:00","description":"DBWC","breadcrumb":{"@id":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/#breadcrumb"},"inLanguage":"en-UK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dbwc.eu\/jahresabschlussball-2021\/"]}]},{"@type":"ImageObject","inLanguage":"en-UK","@id":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/#primaryimage","url":"https:\/\/dbwc.eu\/wp-content\/uploads\/2021\/12\/265240335_650432499287729_6098413531091205400_n.jpg","contentUrl":"https:\/\/dbwc.eu\/wp-content\/uploads\/2021\/12\/265240335_650432499287729_6098413531091205400_n.jpg","width":2038,"height":1359},{"@type":"BreadcrumbList","@id":"https:\/\/dbwc.eu\/jahresabschlussball-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/dbwc.eu\/"},{"@type":"ListItem","position":2,"name":"Jahresabschlussball 2021"}]},{"@type":"WebSite","@id":"https:\/\/dbwc.eu\/#website","url":"https:\/\/dbwc.eu\/","name":"DBWC","description":"Deutsch Belarussischer Wirtschaftsclub","publisher":{"@id":"https:\/\/dbwc.eu\/#organization"},"alternateName":"Deutsch-Belarussischer Wirtschaftsclub","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dbwc.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-UK"},{"@type":"Organization","@id":"https:\/\/dbwc.eu\/#organization","name":"Deutsch-Belarussischer Wirtschaftsclub e.V.","url":"https:\/\/dbwc.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-UK","@id":"https:\/\/dbwc.eu\/#\/schema\/logo\/image\/","url":"https:\/\/dbwc.eu\/wp-content\/uploads\/2021\/12\/logo.svg","contentUrl":"https:\/\/dbwc.eu\/wp-content\/uploads\/2021\/12\/logo.svg","width":237,"height":69,"caption":"Deutsch-Belarussischer Wirtschaftsclub e.V."},"image":{"@id":"https:\/\/dbwc.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/deutschbelarussischer.wirtschaftsclub.9","https:\/\/www.linkedin.com\/company\/deutsch-belarussischer-wirtschaftsclub-e-v\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/dbwc.eu\/#\/schema\/person\/cd3662647974d17cdf3fd25498138a4a","name":"marina.veremchuk","url":"https:\/\/dbwc.eu\/en\/author\/marina-veremchuk\/"}]}},"_links":{"self":[{"href":"https:\/\/dbwc.eu\/en\/wp-json\/wp\/v2\/posts\/7375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dbwc.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dbwc.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dbwc.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dbwc.eu\/en\/wp-json\/wp\/v2\/comments?post=7375"}],"version-history":[{"count":10,"href":"https:\/\/dbwc.eu\/en\/wp-json\/wp\/v2\/posts\/7375\/revisions"}],"predecessor-version":[{"id":7379,"href":"https:\/\/dbwc.eu\/en\/wp-json\/wp\/v2\/posts\/7375\/revisions\/7379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dbwc.eu\/en\/wp-json\/wp\/v2\/media\/7385"}],"wp:attachment":[{"href":"https:\/\/dbwc.eu\/en\/wp-json\/wp\/v2\/media?parent=7375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dbwc.eu\/en\/wp-json\/wp\/v2\/categories?post=7375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dbwc.eu\/en\/wp-json\/wp\/v2\/tags?post=7375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}